{"id":1116,"date":"2019-03-29T17:27:02","date_gmt":"2019-03-29T23:27:02","guid":{"rendered":"http:\/\/www.berthoudhistoricalsociety.org\/?p=1116"},"modified":"2026-04-07T16:00:54","modified_gmt":"2026-04-07T22:00:54","slug":"berthoud-hose-company-no-1","status":"publish","type":"post","link":"https:\/\/berthoudhistoricalsociety.org\/es\/berthoud-hose-company-no-1\/","title":{"rendered":"Compa\u00f1\u00eda de mangueras Berthoud n\u00ba 1."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1116\" class=\"elementor elementor-1116\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7aef19e7 e-flex e-con-boxed e-con e-parent\" data-id=\"7aef19e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7356f7 elementor-widget elementor-widget-heading\" data-id=\"c7356f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Berthoud Host Company No. 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8d531b elementor-widget elementor-widget-image\" data-id=\"b8d531b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"595\" src=\"https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-960x714.jpg\" class=\"attachment-large size-large wp-image-1119\" alt=\"\" srcset=\"https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-960x714.jpg 960w, https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-scaled-300x223.jpg 300w, https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-scaled-600x446.jpg 600w, https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-200x150.jpg 200w, https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-540x402.jpg 540w, https:\/\/berthoudhistoricalsociety.org\/wp-content\/uploads\/2019\/03\/Hose-Team-1-768x572.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa03d99 elementor-widget elementor-widget-text-editor\" data-id=\"1aa03d99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><em>by Mark French<\/em><br \/>El primer equipo de extinci\u00f3n de incendios de la ciudad fue conocido como <b>Compa\u00f1\u00eda de mangueras Berthoud n\u00ba 1.<\/b> Se organiz\u00f3 en mayo de 1888 cuando el juez de paz Ed Willis presidi\u00f3 una reuni\u00f3n celebrada en los \u201csalones de la oficina de correos\u201d. Willis era profesor en la escuela rural de Mars Hill, una milla al norte de Berthoud. La oficina de correos estaba ubicada en la tienda mercantil Bowman, Day &amp; Blackwell en 549 3rd Street. Willis fue elegido presidente temporal de un comit\u00e9 designado para trabajar en una constituci\u00f3n y estatutos y determinar el costo de la manguera y el carro de manguera.<\/p>\n\n<p>En una reuni\u00f3n celebrada en junio de 1888, Matt Rowen fue elegido presidente; Willis, secretario; George Graham, capataz; Andy Fairbairn, asistente del capataz; y H. Leary, segundo asistente del capataz. Tambi\u00e9n se determin\u00f3 que la compa\u00f1\u00eda estar\u00eda desfilando y \u201cestar\u00eda en buen estado de funcionamiento para el 4 de julio\u201d, cuando se celebrar\u00eda un gran baile en el segundo piso del molino harinero reci\u00e9n construido.<\/p>\n\n<p>No ser\u00eda hasta agosto de 1889 que Berthoud Hose Company No. 1 se organizar\u00eda formalmente y se equipar\u00eda con un carro de manguera que hab\u00eda sido comprado por la recientemente incorporada ciudad de Berthoud.<\/p>\n\n<p>Los miembros de la empresa de mangueras fueron iniciados antes del servicio. Para probar la potencia pulmonar, los candidatos deb\u00edan soplar a trav\u00e9s de una manguera suspendida de la torre de la casa de mangueras y forzar 25 libras de agua hasta la cima. Para probar la audici\u00f3n, se mantuvieron erguidos mientras se dirig\u00eda un chorro de agua a m\u00e1xima presi\u00f3n a un o\u00eddo. Para demostrar que sus piernas estaban en condiciones de correr, los colgaron de los pies durante cinco minutos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Berthoud Host Company No. 1 by Mark FrenchThe town\u2019s first fire-fighting team was known as Berthoud Hose Company No. 1. It was organized in May 1888 when Justice of the [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":1119,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"categories":[1],"tags":[],"class_list":["post-1116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/posts\/1116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/comments?post=1116"}],"version-history":[{"count":21,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/posts\/1116\/revisions"}],"predecessor-version":[{"id":22005,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/posts\/1116\/revisions\/22005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/media\/1119"}],"wp:attachment":[{"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/media?parent=1116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/categories?post=1116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berthoudhistoricalsociety.org\/es\/wp-json\/wp\/v2\/tags?post=1116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}